{"id":15356,"date":"2020-08-10T16:00:21","date_gmt":"2020-08-10T16:00:21","guid":{"rendered":"https:\/\/www.cca-acc.com\/cca_goldseal_proj\/the-berkeley-retirement-residence\/"},"modified":"2020-08-10T18:06:46","modified_gmt":"2020-08-10T18:06:46","slug":"the-berkeley-retirement-residence","status":"publish","type":"cca_goldseal_proj","link":"https:\/\/www.cca-acc.com\/fr\/cca_goldseal_proj\/the-berkeley-retirement-residence\/","title":{"rendered":"Le projet de maison de retraite Berkeley"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le projet de maison de retraite Berkeley, r\u00e9alis\u00e9 par Marco Group of Companies, est l\u2019un de deux projets Sceau d\u2019or en cours en Nouvelle-\u00c9cosse. Ce projet a commenc\u00e9 en juin 2019 et devrait \u00eatre termin\u00e9 en janvier 2021.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette nouvelle r\u00e9sidence de retraite est le premier projet r\u00e9alis\u00e9 par Marco pour le compte de l\u2019entreprise The Berkeley. L\u2019immeuble de six \u00e9tages comprendra 76 pi\u00e8ces, avec des studios et des appartements d\u2019une chambre et de deux chambres \u00e0 coucher. L\u2019immeuble aura \u00e9galement 20 salles de soins pour accueillir des r\u00e9sidents atteints de d\u00e9mence. Comme toutes les r\u00e9sidences Berkeley, l\u2019immeuble est situ\u00e9 \u00e0 distance de marche de commerces, dont des \u00e9piceries, des restaurants, des cliniques et des pharmacies. Une fois le projet termin\u00e9, les r\u00e9sidents retrait\u00e9s pourront vivre dans un appartement avec services inclus et b\u00e9n\u00e9ficier de professionnels de la sant\u00e9 sur place 24 heures sur 24.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"415\" src=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-2-500x415-1.jpg\" alt=\"\" data-id=\"15256\" data-full-url=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-2-500x415-1.jpg\" data-link=\"https:\/\/www.cca-acc.com\/?attachment_id=15256\" class=\"wp-image-15256\" srcset=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-2-500x415-1.jpg 500w, https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-2-500x415-1-300x249.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"415\" src=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-500x415-v2.jpg\" alt=\"\" data-id=\"15258\" data-full-url=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-500x415-v2.jpg\" data-link=\"https:\/\/www.cca-acc.com\/?attachment_id=15258\" class=\"wp-image-15258\" srcset=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-500x415-v2.jpg 500w, https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/CANS-Berkley-500x415-v2-300x249.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"257\" src=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/Berkley.jpg\" alt=\"\" data-id=\"15260\" data-full-url=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/Berkley.jpg\" data-link=\"https:\/\/www.cca-acc.com\/?attachment_id=15260\" class=\"wp-image-15260\" srcset=\"https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/Berkley.jpg 600w, https:\/\/www.cca-acc.com\/wp-content\/uploads\/2020\/08\/Berkley-300x129.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"featured_media":15255,"template":"","class_list":["post-15356","cca_goldseal_proj","type-cca_goldseal_proj","status-publish","has-post-thumbnail","hentry","cca_goldseal_proj_location-nouvelle-ecosse"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_goldseal_proj\/15356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_goldseal_proj"}],"about":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/types\/cca_goldseal_proj"}],"version-history":[{"count":0,"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_goldseal_proj\/15356\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/media\/15255"}],"wp:attachment":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/media?parent=15356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}