{"id":73721,"date":"2025-10-24T09:05:00","date_gmt":"2025-10-24T13:05:00","guid":{"rendered":"https:\/\/www.cca-acc.com\/?post_type=cca_plus&#038;p=73721"},"modified":"2025-10-29T11:40:24","modified_gmt":"2025-10-29T15:40:24","slug":"contribuez-a-faconner-lavenir-des-documents-du-ccdc-votre-avis-nous-interesse","status":"publish","type":"cca_plus","link":"https:\/\/www.cca-acc.com\/fr\/plus\/contribuez-a-faconner-lavenir-des-documents-du-ccdc-votre-avis-nous-interesse\/","title":{"rendered":"Contribuez \u00e0 fa\u00e7onner l\u2019avenir des documents du CCDC\u00a0: votre avis nous int\u00e9resse"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019Association canadienne de la construction accorde la plus grande importance \u00e0 l\u2019apport et \u00e0 l\u2019expertise de ses membres. Nous invitons les membres \u00e0 examiner la nouvelle \u00e9bauche de document du Comit\u00e9 canadien des documents de construction (CCDC) indiqu\u00e9e ci-dessous et \u00e0 nous faire part de leurs commentaires&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-brand-color has-text-color has-link-color wp-elements-1\" style=\"font-size:25px\"><strong>CCDC&nbsp;32-G \u00ab&nbsp;Guide du contrat CCDC&nbsp;32 de conception-construction progressive&nbsp;\u00bb.<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">En nous faisant part de vos observations, vous contribuez \u00e0 la cr\u00e9ation d\u2019un cadre qui favorise la collaboration, l\u2019efficacit\u00e9 et la r\u00e9ussite des projets de construction \u00e0 l\u2019\u00e9chelle nationale.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-large-font-size\"><strong>Date limite pour la r\u00e9troaction&nbsp;: 12&nbsp;d\u00e9cembre&nbsp;2025<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Veuillez communiquer avec <a href=\"mailto:zmullins@cca-acc.com\" target=\"_blank\" rel=\"noreferrer noopener\">Zachary Mullins<\/a>&nbsp;si vous aimeriez examiner l\u2019\u00e9bauche mentionn\u00e9e ci-dessus.<\/p>\n","protected":false},"featured_media":73720,"menu_order":0,"template":"","class_list":["post-73721","cca_plus","type-cca_plus","status-publish","has-post-thumbnail","hentry","cca_plus_category-cap-sur-les-pratiques-exemplaires","cca_plus_category-focus-on-best-practices"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_plus\/73721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_plus"}],"about":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/types\/cca_plus"}],"version-history":[{"count":4,"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_plus\/73721\/revisions"}],"predecessor-version":[{"id":73729,"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/cca_plus\/73721\/revisions\/73729"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/media\/73720"}],"wp:attachment":[{"href":"https:\/\/www.cca-acc.com\/fr\/wp-json\/wp\/v2\/media?parent=73721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}